{"id":313,"count":1,"description":"","link":"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/","name":"Art &amp; Philosophy","slug":"art-philosophy","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Art &amp; Philosophy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Art &amp; Philosophy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9ric Petr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eoroioco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/en\\\/blogue\\\/tag\\\/art-philosophy\\\/\",\"url\":\"https:\\\/\\\/www.ericpetr.net\\\/en\\\/blogue\\\/tag\\\/art-philosophy\\\/\",\"name\":\"Archives des Art &amp; Philosophy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/en\\\/blogue\\\/tag\\\/art-philosophy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/en\\\/blogue\\\/tag\\\/art-philosophy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ericpetr.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art &amp; Philosophy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/#website\",\"url\":\"https:\\\/\\\/www.ericpetr.net\\\/\",\"name\":\"\u00c9ric Petr\",\"description\":\"photographe plasticien\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/#\\\/schema\\\/person\\\/8f2d488e548d63fb891b6fed188f8ad8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ericpetr.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/#\\\/schema\\\/person\\\/8f2d488e548d63fb891b6fed188f8ad8\",\"name\":\"\u00c9ric PETR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/EP_0x8B25604.jpg\",\"url\":\"https:\\\/\\\/www.ericpetr.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/EP_0x8B25604.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ericpetr.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/EP_0x8B25604.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"\u00c9ric PETR\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.ericpetr.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/EP_0x8B25604.jpg\"},\"description\":\"Artiste visuel, je suis ouvert \u00e0 tout projet artistique, d\u2019exposition ou pour toute commande personnalis\u00e9e. Mes \u0153uvres sont en vente en \u00e9dition limit\u00e9e et je vous invite pour cela \u00e0 visiter ma galerie sur Artmajeur.\",\"sameAs\":[\"https:\\\/\\\/www.ericpetr.net\",\"https:\\\/\\\/www.facebook.com\\\/photography.ericPetr\\\/\",\"https:\\\/\\\/www.instagram.com\\\/petr.eric\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/eric-petr-a888z\\\/\",\"https:\\\/\\\/x.com\\\/eoroioco\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Art &amp; Philosophy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Art &amp; Philosophy","og_url":"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/","og_site_name":"\u00c9ric Petr","twitter_card":"summary_large_image","twitter_site":"@eoroioco","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/","url":"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/","name":"Archives des Art &amp; Philosophy","isPartOf":{"@id":"https:\/\/www.ericpetr.net\/#website"},"breadcrumb":{"@id":"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ericpetr.net\/en\/blogue\/tag\/art-philosophy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ericpetr.net\/en\/"},{"@type":"ListItem","position":2,"name":"Art &amp; Philosophy"}]},{"@type":"WebSite","@id":"https:\/\/www.ericpetr.net\/#website","url":"https:\/\/www.ericpetr.net\/","name":"\u00c9ric Petr","description":"photographe plasticien","publisher":{"@id":"https:\/\/www.ericpetr.net\/#\/schema\/person\/8f2d488e548d63fb891b6fed188f8ad8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ericpetr.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.ericpetr.net\/#\/schema\/person\/8f2d488e548d63fb891b6fed188f8ad8","name":"\u00c9ric PETR","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ericpetr.net\/wp-content\/uploads\/2021\/12\/EP_0x8B25604.jpg","url":"https:\/\/www.ericpetr.net\/wp-content\/uploads\/2021\/12\/EP_0x8B25604.jpg","contentUrl":"https:\/\/www.ericpetr.net\/wp-content\/uploads\/2021\/12\/EP_0x8B25604.jpg","width":1200,"height":1200,"caption":"\u00c9ric PETR"},"logo":{"@id":"https:\/\/www.ericpetr.net\/wp-content\/uploads\/2021\/12\/EP_0x8B25604.jpg"},"description":"Artiste visuel, je suis ouvert \u00e0 tout projet artistique, d\u2019exposition ou pour toute commande personnalis\u00e9e. Mes \u0153uvres sont en vente en \u00e9dition limit\u00e9e et je vous invite pour cela \u00e0 visiter ma galerie sur Artmajeur.","sameAs":["https:\/\/www.ericpetr.net","https:\/\/www.facebook.com\/photography.ericPetr\/","https:\/\/www.instagram.com\/petr.eric\/","https:\/\/www.linkedin.com\/in\/eric-petr-a888z\/","https:\/\/x.com\/eoroioco"]}]}},"_links":{"self":[{"href":"https:\/\/www.ericpetr.net\/en\/wp-json\/wp\/v2\/tags\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ericpetr.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ericpetr.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ericpetr.net\/en\/wp-json\/wp\/v2\/posts?tags=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}